{"id":6789,"date":"2025-07-26T07:29:07","date_gmt":"2025-07-26T07:29:07","guid":{"rendered":"https:\/\/geoambient.cat\/?page_id=6789"},"modified":"2025-08-05T06:33:13","modified_gmt":"2025-08-05T06:33:13","slug":"aguas-residuales","status":"publish","type":"page","link":"https:\/\/geoambient.cat\/es\/aguas-residuales\/","title":{"rendered":"Aguas residuales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6789\" class=\"elementor elementor-6789 elementor-6802\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8a65de sld e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"d8a65de\" data-element_type=\"container\" id=\"sld\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;\\\/wp-content\\\/themes\\\/geoambient-kit-child\\\/Videos\\\/used\\\/aguas-residuales\\\/urbanas.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-1b201e4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1b201e4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aguas residuales<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3722c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3e3722c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda para el medio ambiente, eficacia para tu proyecto.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e594bd5 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"e594bd5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7394946 elementor-widget elementor-widget-heading\" data-id=\"7394946\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soluciones sostenibles para el tratamiento de aguas residuales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de5e4c elementor-widget elementor-widget-heading\" data-id=\"1de5e4c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tecnolog\u00edas ecol\u00f3gicas y de alto rendimiento para usos industriales, urbanos y lixiviados<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16c7546 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"16c7546\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-568e15c e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible e-con e-child\" data-id=\"568e15c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f59efd elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1f59efd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/05\/Aguas_Residuales-Urbanas-EDAR-de-Montcarra.jpg\" class=\"attachment-full size-full wp-image-4052\" alt=\"EDAR de Montcarra\" srcset=\"https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/05\/Aguas_Residuales-Urbanas-EDAR-de-Montcarra.jpg 1200w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/05\/Aguas_Residuales-Urbanas-EDAR-de-Montcarra-300x225.jpg 300w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/05\/Aguas_Residuales-Urbanas-EDAR-de-Montcarra-1024x768.jpg 1024w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/05\/Aguas_Residuales-Urbanas-EDAR-de-Montcarra-768x576.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24b18e7 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible e-con e-child\" data-id=\"24b18e7\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e84e4b elementor-widget elementor-widget-text-editor\" data-id=\"1e84e4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"0\" data-end=\"190\"><strong>GeoAmbient<\/strong>, junto con <strong>SERFIM GROUPE<\/strong> y <strong>SERPOL<\/strong>, ofrece soluciones integrales y de alcance global para la rehabilitaci\u00f3n de suelos contaminados, tratamiento de aguas residuales e hidrogeolog\u00eda.<\/p><p data-start=\"192\" data-end=\"522\" data-is-last-node=\"\" data-is-only-node=\"\">Presentamos nuestra soluci\u00f3n avanzada para la depuraci\u00f3n de aguas en comunidades de hasta 2.000 habitantes: tecnolog\u00edas sostenibles de bajo consumo energ\u00e9tico y mantenimiento, sin productos qu\u00edmicos y dise\u00f1adas para integrarse perfectamente en el paisaje. Ideal para localidades peque\u00f1as que buscan eficiencia y respeto ambiental.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b417561 wpr-button-icon-style-inline wpr-button-icon-position-right elementor-widget elementor-widget-wpr-button\" data-id=\"b417561\" data-element_type=\"widget\" data-widget_type=\"wpr-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t\t\n\t\t\n\t\t<div class=\"wpr-button-wrap elementor-clearfix\">\n\t\t<a class=\"wpr-button wpr-button-effect wpr-button-isi-left\" data-text=\"\" href=\"https:\/\/geoambient.cat\/es\/referencias-es\/\">\n\t\t\t\n\t\t\t<span class=\"wpr-button-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"wpr-button-text\">Referencias<\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85b5882 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"85b5882\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03e3cab elementor-widget elementor-widget-heading\" data-id=\"03e3cab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tratamiento integral de aguas residuales urbanas, industriales y lixiviados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00d1279 e-grid e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"00d1279\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83ac39a e-con-full e-flex wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"83ac39a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7563c9e wpr-flip-box-animation-zoom-out wpr-flip-box-front-align-center wpr-flip-box-back-align-center elementor-widget elementor-widget-wpr-flip-box\" data-id=\"7563c9e\" data-element_type=\"widget\" data-widget_type=\"wpr-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t<div class=\"wpr-flip-box\" data-trigger=\"hover\">\n\t\t\t\n\t\t\t<div class=\"wpr-flip-box-item wpr-flip-box-front wpr-anim-timing-ease-default\">\n\n\t\t\t\t<div class=\"wpr-flip-box-overlay\"><\/div>\n\n\t\t\t\t<div class=\"wpr-flip-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"wpr-flip-box-title\">Industriales<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"wpr-flip-box-item wpr-flip-box-back wpr-anim-timing-ease-default\">\n\n\t\t\t\t<div class=\"wpr-flip-box-overlay\"><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wpr-flip-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-flip-box-description\"><p><strong>GeoAmbient<\/strong> innova con las t\u00e9cnicas m\u00e1s sostenibles realizando un dise\u00f1o ajustado a vuestras necesidades espec\u00edficas, redactando el proyecto ejecutivo y coordinando la instalaci\u00f3n para alcanzar los objetivos de tratamiento definidos.<\/p><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wpr-flip-box-btn-wrap\">\n\t\t\t\t\t\t\t<a class=\"wpr-flip-box-btn\" href=\"https:\/\/geoambient.cat\/es\/industriales\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-flip-box-btn-text\">Ver m\u00e1s<\/span>\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22a8f1a e-con-full e-flex wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"22a8f1a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cceb8b3 wpr-flip-box-animation-zoom-out wpr-flip-box-front-align-center wpr-flip-box-back-align-center elementor-widget elementor-widget-wpr-flip-box\" data-id=\"cceb8b3\" data-element_type=\"widget\" data-widget_type=\"wpr-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t<div class=\"wpr-flip-box\" data-trigger=\"hover\">\n\t\t\t\n\t\t\t<div class=\"wpr-flip-box-item wpr-flip-box-front wpr-anim-timing-ease-default\">\n\n\t\t\t\t<div class=\"wpr-flip-box-overlay\"><\/div>\n\n\t\t\t\t<div class=\"wpr-flip-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"wpr-flip-box-title\">Urbanas<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"wpr-flip-box-item wpr-flip-box-back wpr-anim-timing-ease-default\">\n\n\t\t\t\t<div class=\"wpr-flip-box-overlay\"><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wpr-flip-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-flip-box-description\"><p><strong>GeoAmbient<\/strong> dise\u00f1a y construye plantas de tratamiento de aguas residuales sanitarias para n\u00facleos de hasta 2.000 Hab. Eq. con las t\u00e9cnicas m\u00e1s innovadoras, bases de flujo vertical y\/o horizontal, biodiscos, tanques Imhoff, pretratamientos automatizados, sistemas de reutilizaci\u00f3n y adaptaciones a las necesidades espec\u00edficas.<\/p><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wpr-flip-box-btn-wrap\">\n\t\t\t\t\t\t\t<a class=\"wpr-flip-box-btn\" href=\"https:\/\/geoambient.cat\/es\/urbanas\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-flip-box-btn-text\">Ver m\u00e1s<\/span>\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18fdbde e-con-full e-flex wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"18fdbde\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db12761 wpr-flip-box-animation-zoom-out wpr-flip-box-front-align-center wpr-flip-box-back-align-center elementor-widget elementor-widget-wpr-flip-box\" data-id=\"db12761\" data-element_type=\"widget\" data-widget_type=\"wpr-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t<div class=\"wpr-flip-box\" data-trigger=\"hover\">\n\t\t\t\n\t\t\t<div class=\"wpr-flip-box-item wpr-flip-box-front wpr-anim-timing-ease-default\">\n\n\t\t\t\t<div class=\"wpr-flip-box-overlay\"><\/div>\n\n\t\t\t\t<div class=\"wpr-flip-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"wpr-flip-box-title\">Lixiviados<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"wpr-flip-box-item wpr-flip-box-back wpr-anim-timing-ease-default\">\n\n\t\t\t\t<div class=\"wpr-flip-box-overlay\"><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wpr-flip-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-flip-box-description\"><p><strong>GeoAmbient<\/strong> dise\u00f1a e instala plantas de tratamiento para cada tipolog\u00eda de vertedero adaptadas a la composici\u00f3n espec\u00edfica de los lixiviados.<\/p><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wpr-flip-box-btn-wrap\">\n\t\t\t\t\t\t\t<a class=\"wpr-flip-box-btn\" href=\"https:\/\/geoambient.cat\/es\/lixiviados\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-flip-box-btn-text\">Ver m\u00e1s<\/span>\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5489681 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"5489681\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-969b7d6 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible e-con e-child\" data-id=\"969b7d6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd550e3 elementor-widget elementor-widget-heading\" data-id=\"fd550e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Humedales artificiales: Una EDAR sostenible con un mantenimiento m\u00ednimo.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc7d08d elementor-widget elementor-widget-text-editor\" data-id=\"dc7d08d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Un sistema de depuraci\u00f3n de aguas residuales eficiente, econ\u00f3mico, sin olores, integrado en el paisaje y adaptable a comunidades de menos de 2.000 habitantes equivalentes.<\/strong><\/p><p>Durante 2024, en <strong>GeoAmbient<\/strong> dise\u00f1amos y construimos una estaci\u00f3n depuradora de aguas residuales (EDAR) en el n\u00facleo urbano de Benasau (Alicante), para una poblaci\u00f3n de 150 habitantes equivalentes.<\/p><p>Esta EDAR utiliza humedales artificiales de flujo vertical y horizontal con vegetaci\u00f3n adaptada, que favorece el desarrollo de biomasa bacteriana aer\u00f3bica y anaer\u00f3bica, capaz de degradar los compuestos org\u00e1nicos y nitrogenados presentes en las aguas residuales urbanas.<\/p><p>Gracias a un sistema de pretratamiento alimentado con energ\u00eda solar, esta EDAR no requiere conexi\u00f3n a la red el\u00e9ctrica, permitiendo un funcionamiento sostenible y un mantenimiento m\u00ednimo.<\/p><p>Mediante la combinaci\u00f3n de pretratamiento, biodiscos, dep\u00f3sitos digestores y humedales artificiales, dise\u00f1amos la soluci\u00f3n ideal para el tratamiento de aguas residuales en peque\u00f1os n\u00facleos urbanos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e25894 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible e-con e-child\" data-id=\"5e25894\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6be8a4 elementor-widget elementor-widget-video\" data-id=\"a6be8a4\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/geoambient.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DJI_0246-ar-scaled.jpg&quot;,&quot;id&quot;:6569,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;lightbox&quot;:&quot;yes&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-lightbox\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;hosted&quot;,&quot;url&quot;:&quot;https:\\\/\\\/geoambient.cat\\\/wp-content\\\/themes\\\/geoambient-kit-child\\\/Videos\\\/Servicios\\\/Aguas_Residuales\\\/1_Ares_del_Bosc\\\/1721_ARES_DEL_BOSC.mp4&quot;,&quot;autoplay&quot;:&quot;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-a6be8a4&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;},&quot;videoParams&quot;:{&quot;controls&quot;:&quot;&quot;,&quot;preload&quot;:&quot;metadata&quot;,&quot;controlsList&quot;:&quot;nodownload&quot;,&quot;poster&quot;:&quot;https:\\\/\\\/geoambient.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DJI_0246-ar-scaled.jpg&quot;}}\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJob3N0ZWQiLCJ1cmwiOiJodHRwczpcL1wvZ2VvYW1iaWVudC5jYXRcL3dwLWNvbnRlbnRcL3RoZW1lc1wvZ2VvYW1iaWVudC1raXQtY2hpbGRcL1ZpZGVvc1wvU2VydmljaW9zXC9BZ3Vhc19SZXNpZHVhbGVzXC8xX0FyZXNfZGVsX0Jvc2NcLzE3MjFfQVJFU19ERUxfQk9TQy5tcDQiLCJhdXRvcGxheSI6IiIsIm1vZGFsT3B0aW9ucyI6eyJpZCI6ImVsZW1lbnRvci1saWdodGJveC1hNmJlOGE0IiwiZW50cmFuY2VBbmltYXRpb24iOiIiLCJlbnRyYW5jZUFuaW1hdGlvbl90YWJsZXQiOiIiLCJlbnRyYW5jZUFuaW1hdGlvbl9tb2JpbGUiOiIiLCJ2aWRlb0FzcGVjdFJhdGlvIjoiMTY5In0sInZpZGVvUGFyYW1zIjp7ImNvbnRyb2xzIjoiIiwicHJlbG9hZCI6Im1ldGFkYXRhIiwiY29udHJvbHNMaXN0Ijoibm9kb3dubG9hZCIsInBvc3RlciI6Imh0dHBzOlwvXC9nZW9hbWJpZW50LmNhdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDdcL0RKSV8wMjQ2LWFyLXNjYWxlZC5qcGcifX0%3D\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/DJI_0246-ar-scaled.jpg\" class=\"attachment-full size-full wp-image-6569\" alt=\"\" srcset=\"https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/DJI_0246-ar-scaled.jpg 2560w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/DJI_0246-ar-300x169.jpg 300w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/DJI_0246-ar-1024x576.jpg 1024w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/DJI_0246-ar-768x432.jpg 768w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/DJI_0246-ar-1536x864.jpg 1536w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/DJI_0246-ar-2048x1152.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-play\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M838 162C746 71 633 25 500 25 371 25 258 71 163 162 71 254 25 367 25 500 25 633 71 746 163 837 254 929 367 979 500 979 633 979 746 933 838 837 929 746 975 633 975 500 975 367 929 254 838 162M808 192C892 279 933 379 933 500 933 621 892 725 808 808 725 892 621 938 500 938 379 938 279 896 196 808 113 725 67 621 67 500 67 379 108 279 196 192 279 108 383 62 500 62 621 62 721 108 808 192M438 392V642L642 517 438 392Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66bb3f7 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"66bb3f7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25a1ca7 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible e-con e-child\" data-id=\"25a1ca7\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-457de00 elementor-widget elementor-widget-video\" data-id=\"457de00\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/geoambient.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2_Roseaulix-scaled.png&quot;,&quot;id&quot;:6485,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;2_Roseaulix&quot;,&quot;source&quot;:&quot;library&quot;},&quot;lightbox&quot;:&quot;yes&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-lightbox\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;hosted&quot;,&quot;url&quot;:&quot;https:\\\/\\\/geoambient.cat\\\/wp-content\\\/themes\\\/geoambient-kit-child\\\/Videos\\\/Servicios\\\/Aguas_Residuales\\\/2_Roseaulix\\\/GeoAmbient_Roseaulix_HD.mp4\\t&quot;,&quot;autoplay&quot;:&quot;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-457de00&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;},&quot;videoParams&quot;:{&quot;controls&quot;:&quot;&quot;,&quot;preload&quot;:&quot;auto&quot;,&quot;controlsList&quot;:&quot;nodownload&quot;,&quot;poster&quot;:&quot;https:\\\/\\\/geoambient.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2_Roseaulix-scaled.png&quot;}}\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJob3N0ZWQiLCJ1cmwiOiJodHRwczpcL1wvZ2VvYW1iaWVudC5jYXRcL3dwLWNvbnRlbnRcL3RoZW1lc1wvZ2VvYW1iaWVudC1raXQtY2hpbGRcL1ZpZGVvc1wvU2VydmljaW9zXC9BZ3Vhc19SZXNpZHVhbGVzXC8yX1Jvc2VhdWxpeFwvR2VvQW1iaWVudF9Sb3NlYXVsaXhfSEQubXA0XHQiLCJhdXRvcGxheSI6IiIsIm1vZGFsT3B0aW9ucyI6eyJpZCI6ImVsZW1lbnRvci1saWdodGJveC00NTdkZTAwIiwiZW50cmFuY2VBbmltYXRpb24iOiIiLCJlbnRyYW5jZUFuaW1hdGlvbl90YWJsZXQiOiIiLCJlbnRyYW5jZUFuaW1hdGlvbl9tb2JpbGUiOiIiLCJ2aWRlb0FzcGVjdFJhdGlvIjoiMTY5In0sInZpZGVvUGFyYW1zIjp7ImNvbnRyb2xzIjoiIiwicHJlbG9hZCI6ImF1dG8iLCJjb250cm9sc0xpc3QiOiJub2Rvd25sb2FkIiwicG9zdGVyIjoiaHR0cHM6XC9cL2dlb2FtYmllbnQuY2F0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wN1wvMl9Sb3NlYXVsaXgtc2NhbGVkLnBuZyJ9fQ%3D%3D\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1404\" src=\"https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/2_Roseaulix-scaled.png\" class=\"attachment-full size-full wp-image-6485\" alt=\"2_Roseaulix\" srcset=\"https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/2_Roseaulix-scaled.png 2560w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/2_Roseaulix-300x165.png 300w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/2_Roseaulix-1024x562.png 1024w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/2_Roseaulix-768x421.png 768w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/2_Roseaulix-1536x842.png 1536w, https:\/\/geoambient.cat\/wp-content\/uploads\/2025\/07\/2_Roseaulix-2048x1123.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir video acerca de 2_Roseaulix\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-play\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M838 162C746 71 633 25 500 25 371 25 258 71 163 162 71 254 25 367 25 500 25 633 71 746 163 837 254 929 367 979 500 979 633 979 746 933 838 837 929 746 975 633 975 500 975 367 929 254 838 162M808 192C892 279 933 379 933 500 933 621 892 725 808 808 725 892 621 938 500 938 379 938 279 896 196 808 113 725 67 621 67 500 67 379 108 279 196 192 279 108 383 62 500 62 621 62 721 108 808 192M438 392V642L642 517 438 392Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-508c226 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible e-con e-child\" data-id=\"508c226\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1dbae3 elementor-widget elementor-widget-heading\" data-id=\"e1dbae3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Roseaulix: Tratamiento de lixiviados en vertederos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da84013 elementor-widget elementor-widget-text-editor\" data-id=\"da84013\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"0\" data-end=\"88\"><strong>Simbiosis entre bacterias y vegetaci\u00f3n para eliminar compuestos org\u00e1nicos y nitrogenados<\/strong><\/p><p data-start=\"90\" data-end=\"300\">En colaboraci\u00f3n con Serpol, dise\u00f1amos, instalamos y operamos desde 2012 una planta de tratamiento de lixiviados en un vertedero de residuos no peligrosos en Vaux-en-Bugey, en la regi\u00f3n de Auvernia-R\u00f3dano-Alpes.<\/p><p data-start=\"302\" data-end=\"575\">La tecnolog\u00eda ROSEAULIX utiliza humedales artificiales de flujo vertical y horizontal que favorecen el desarrollo de biomasa bacteriana aer\u00f3bica y anaer\u00f3bica, capaz de degradar los compuestos org\u00e1nicos y nitrogenados presentes en los lixiviados de la mayor\u00eda de vertederos.<\/p><p data-start=\"577\" data-end=\"838\" data-is-last-node=\"\" data-is-only-node=\"\">El sistema incorpora un cuadro el\u00e9ctrico automatizado con telegesti\u00f3n, que permite un funcionamiento aut\u00f3nomo durante todo el a\u00f1o, con un mantenimiento m\u00ednimo, bajo costo y una vida \u00fatil de m\u00e1s de 20 a\u00f1os, sin necesidad de gestionar los lodos de manera externa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab161c1 elementor-widget elementor-widget-text-editor\" data-id=\"ab161c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #60afdd;\"><strong>ROSEAULIX es la soluci\u00f3n m\u00e1s vers\u00e1til y sostenible para el tratamiento de lixiviados en vertederos.<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccce948 e-flex e-con-boxed wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"ccce948\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a760e24 elementor-widget elementor-widget-heading\" data-id=\"a760e24\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contacta con nosotros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b79895b frm-sys elementor-widget elementor-widget-shortcode\" data-id=\"b79895b\" data-element_type=\"widget\" id=\"frm-sys\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6619-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"6619\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/6789#wpcf7-f6619-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6619\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6619-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre y Apellidos\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-748\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" autocomplete=\"tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"tel-748\" \/><\/span><\/label>\n<\/p>\n<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"select-971\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"select-971\"><option value=\"\">Asunto<\/option><option value=\"Contacto\">Contacto<\/option><option value=\"Suelos contaminados\">Suelos contaminados<\/option><option value=\"Aguas residuales\">Aguas residuales<\/option><option value=\"Valorizaci\u00f3n\">Valorizaci\u00f3n<\/option><option value=\"I+D+i\">I+D+i<\/option><option value=\"Trabaja con nosotros\">Trabaja con nosotros<\/option><option value=\"Otros\">Otros<\/option><\/select><\/span><\/label>\n<\/p>\n<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"2\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><span id=\"wpcf7-6a04732b56704-wrapper\" class=\"wpcf7-form-control-wrap honeypot-935-wrap\" style=\"display:none !important; visibility:hidden !important;\"><input type=\"hidden\" name=\"honeypot-935-time-start\" value=\"1778676523\"><input type=\"hidden\" name=\"honeypot-935-time-check\" value=\"7\"><label for=\"wpcf7-6a04732b56704-field\" class=\"hp-message\">Por favor, deja este campo vac\u00edo.<\/label><input id=\"wpcf7-6a04732b56704-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"honeypot-935\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n<\/p>\n<div class=\"privacy-div\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-733\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-733\" value=\"1\" class=\"privacy-es\" id=\"privacy-es\" aria-invalid=\"false\" \/><\/span><\/span><\/span>He le\u00eddo y acepto la <a href=\"https:\/\/geoambient.cat\/es\/politica-de-privacidad\/\" target=\"_blank\" rel=\"noopener\">pol\u00edtica de privacidad<\/a> .\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aguas residuales Ingenier\u00eda para el medio ambiente, eficacia para tu proyecto. Soluciones sostenibles para el tratamiento de aguas residuales Tecnolog\u00edas ecol\u00f3gicas y de alto rendimiento para usos industriales, urbanos y lixiviados GeoAmbient, junto con SERFIM GROUPE y SERPOL, ofrece soluciones integrales y de alcance global para la rehabilitaci\u00f3n de suelos contaminados, tratamiento de aguas residuales e hidrogeolog\u00eda. Presentamos nuestra soluci\u00f3n avanzada para la depuraci\u00f3n de aguas en comunidades de hasta 2.000 habitantes: tecnolog\u00edas sostenibles de bajo consumo energ\u00e9tico y mantenimiento, sin productos qu\u00edmicos y dise\u00f1adas para integrarse perfectamente en el paisaje. Ideal para localidades peque\u00f1as que buscan eficiencia y respeto ambiental. Referencias Tratamiento integral de aguas residuales urbanas, industriales y lixiviados Industriales GeoAmbient innova con las t\u00e9cnicas m\u00e1s sostenibles realizando un dise\u00f1o ajustado a vuestras necesidades espec\u00edficas, redactando el proyecto ejecutivo y coordinando la instalaci\u00f3n para alcanzar los objetivos de tratamiento definidos. Ver m\u00e1s Urbanas GeoAmbient dise\u00f1a y construye plantas de tratamiento de aguas residuales sanitarias para n\u00facleos de hasta 2.000 Hab. Eq. con las t\u00e9cnicas m\u00e1s innovadoras, bases de flujo vertical y\/o horizontal, biodiscos, tanques Imhoff, pretratamientos automatizados, sistemas de reutilizaci\u00f3n y adaptaciones a las necesidades espec\u00edficas. Ver m\u00e1s Lixiviados GeoAmbient dise\u00f1a e instala plantas de tratamiento para cada tipolog\u00eda de vertedero adaptadas a la composici\u00f3n espec\u00edfica de los lixiviados. Ver m\u00e1s Humedales artificiales: Una EDAR sostenible con un mantenimiento m\u00ednimo. Un sistema de depuraci\u00f3n de aguas residuales eficiente, econ\u00f3mico, sin olores, integrado en el paisaje y adaptable a comunidades de menos de 2.000 habitantes equivalentes. Durante 2024, en GeoAmbient dise\u00f1amos y construimos una estaci\u00f3n depuradora de aguas residuales (EDAR) en el n\u00facleo urbano de Benasau (Alicante), para una poblaci\u00f3n de 150 habitantes equivalentes. Esta EDAR utiliza humedales artificiales de flujo vertical y horizontal con vegetaci\u00f3n adaptada, que favorece el desarrollo de biomasa bacteriana aer\u00f3bica y anaer\u00f3bica, capaz de degradar los compuestos org\u00e1nicos y nitrogenados presentes en las aguas residuales urbanas. Gracias a un sistema de pretratamiento alimentado con energ\u00eda solar, esta EDAR no requiere conexi\u00f3n a la red el\u00e9ctrica, permitiendo un funcionamiento sostenible y un mantenimiento m\u00ednimo. Mediante la combinaci\u00f3n de pretratamiento, biodiscos, dep\u00f3sitos digestores y humedales artificiales, dise\u00f1amos la soluci\u00f3n ideal para el tratamiento de aguas residuales en peque\u00f1os n\u00facleos urbanos. https:\/\/geoambient.cat\/wp-content\/themes\/geoambient-kit-child\/Videos\/Servicios\/Aguas_Residuales\/1_Ares_del_Bosc\/1721_ARES_DEL_BOSC.mp4https:\/\/geoambient.cat\/wp-content\/themes\/geoambient-kit-child\/Videos\/Servicios\/Aguas_Residuales\/2_Roseaulix\/GeoAmbient_Roseaulix_HD.mp4 Roseaulix: Tratamiento de lixiviados en vertederos Simbiosis entre bacterias y vegetaci\u00f3n para eliminar compuestos org\u00e1nicos y nitrogenados En colaboraci\u00f3n con Serpol, dise\u00f1amos, instalamos y operamos desde 2012 una planta de tratamiento de lixiviados en un vertedero de residuos no peligrosos en Vaux-en-Bugey, en la regi\u00f3n de Auvernia-R\u00f3dano-Alpes. La tecnolog\u00eda ROSEAULIX utiliza humedales artificiales de flujo vertical y horizontal que favorecen el desarrollo de biomasa bacteriana aer\u00f3bica y anaer\u00f3bica, capaz de degradar los compuestos org\u00e1nicos y nitrogenados presentes en los lixiviados de la mayor\u00eda de vertederos. El sistema incorpora un cuadro el\u00e9ctrico automatizado con telegesti\u00f3n, que permite un funcionamiento aut\u00f3nomo durante todo el a\u00f1o, con un mantenimiento m\u00ednimo, bajo costo y una vida \u00fatil de m\u00e1s de 20 a\u00f1os, sin necesidad de gestionar los lodos de manera externa. ROSEAULIX es la soluci\u00f3n m\u00e1s vers\u00e1til y sostenible para el tratamiento de lixiviados en vertederos. Contacta con nosotros<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-6789","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/pages\/6789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/comments?post=6789"}],"version-history":[{"count":10,"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/pages\/6789\/revisions"}],"predecessor-version":[{"id":7911,"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/pages\/6789\/revisions\/7911"}],"wp:attachment":[{"href":"https:\/\/geoambient.cat\/es\/wp-json\/wp\/v2\/media?parent=6789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}